{"id":1006,"date":"2016-02-17T20:43:30","date_gmt":"2016-02-17T18:43:30","guid":{"rendered":"http:\/\/www.inkultura-online.de\/politisch_unkorrekt\/?p=1006"},"modified":"2016-02-17T20:45:18","modified_gmt":"2016-02-17T18:45:18","slug":"merkel-macht-den-hitler","status":"publish","type":"post","link":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/merkel-macht-den-hitler\/","title":{"rendered":"Merkel macht den Hitler"},"content":{"rendered":"<p>Wie die Geschichte sich doch immer wiederholt. Propagierte der Gr\u00f6FaZ angesichts der sich abzeichnenden Niederlage immer vehementer den \u201eEndsieg\u201c, der, so sein Reichsminister f\u00fcr Volksaufkl\u00e4rung und Propaganda, Joseph Goebbels, nur mittels \u201etotalem Krieg\u201c zu erreichen sei, schwadroniert die Gr\u00f6KaZ kognitiv dissonant von einer Mehrheit der Deutschen, die ihren politischen Wahnsinn unterst\u00fctzt. M\u00fc\u00dfig zu erw\u00e4hnen, dass beide \u2013 Hitler und Goebbels &#8211; sich der Verantwortung durch Suizid entzogen. Wie das bei der Kanzlerin sein wird, bleibt abzuwarten&#8230;<!--more--><\/p>\n<p>Heute, nach der Regierungserkl\u00e4rung der Gr\u00f6KaZ, erinnert die verantwortungslose Politik der Kanzlerin bez\u00fcglich des ungehemmten Einstr\u00f6mens von bald Millionen Menschen nach Deutschland und die Sichtweise der Verursacherin stark an die Durchhalteparolen der Nazi-Eliten, die l\u00e4ngst darum wussten, dass der Krieg und auch das Volk verloren waren.<\/p>\n<p>90 Prozent der Deutschen stehen, so t\u00f6nt Hitlers M\u00e4dchen, hinsichtlich ihrer volksverr\u00e4terischen Politik hinter der Kanzlerin. Lange Zeit hat es gebraucht, aber jetzt schl\u00e4gt die Ost-Sozialisierung der Gr\u00f6KaZ richtig durch. Zu DDR Volkskammerzeiten waren es auch nie weniger als 90 Prozent, meistens kurioserweise 110 Prozent der B\u00fcrger, die sich bei den \u201eWahlen\u201c f\u00fcr die Partei des Fortschritts entschieden haben.<\/p>\n<p>Dass sich Merkel au\u00dferdem f\u00fcr eine engere Zusammenarbeit mit der T\u00fcrkei ausspricht, die offen zugibt, Europa, besonders aber Deutschland mit ihrer Haltung in der Fl\u00fcchtlingsfrage zu erpressen und zudem einer der Hauptverantwortlichen f\u00fcr den Terror in Syrien und aktiver Unterst\u00fctzer des IS ist, beweist, wie sehr die Kanzlerin den Bezug zur politischen Realit\u00e4t verloren hat. Da ist sie, historisch betrachtet, in guter Gesellschaft. Auch der Gr\u00f6FaZ tr\u00e4umte kurz vor dem Ende von den \u201eWunderwaffen\u201c, die angeblich den Verlauf des Krieges zugunsten Deutschlands ver\u00e4ndern sollten.<\/p>\n<p>Wie gesagt, Geschichte wiederholt sich.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie die Geschichte sich doch immer wiederholt. Propagierte der Gr\u00f6FaZ angesichts der sich abzeichnenden Niederlage immer vehementer den \u201eEndsieg\u201c, der, so sein Reichsminister f\u00fcr Volksaufkl\u00e4rung und Propaganda, Joseph Goebbels, nur mittels \u201etotalem Krieg\u201c zu erreichen sei, schwadroniert die Gr\u00f6KaZ kognitiv &hellip; <a href=\"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/merkel-macht-den-hitler\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[378,3,444,10],"tags":[594,451,64,593,81,164],"class_list":["post-1006","post","type-post","status-publish","format-standard","hentry","category-denunzianten","category-die-duemmsten-sprueche-der-woche","category-gedanken-zum-tag","category-systemfehler","tag-endsieg","tag-groefaz","tag-groekaz","tag-hitler","tag-merkel","tag-volksverrat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Merkel macht den Hitler - Zeitgeist? Frei!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/merkel-macht-den-hitler\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Merkel macht den Hitler - Zeitgeist? Frei!\" \/>\n<meta property=\"og:description\" content=\"Wie die Geschichte sich doch immer wiederholt. Propagierte der Gr\u00f6FaZ angesichts der sich abzeichnenden Niederlage immer vehementer den \u201eEndsieg\u201c, der, so sein Reichsminister f\u00fcr Volksaufkl\u00e4rung und Propaganda, Joseph Goebbels, nur mittels \u201etotalem Krieg\u201c zu erreichen sei, schwadroniert die Gr\u00f6KaZ kognitiv &hellip; Weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/merkel-macht-den-hitler\/\" \/>\n<meta property=\"og:site_name\" content=\"Zeitgeist? Frei!\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-17T18:43:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-17T18:45:18+00:00\" \/>\n<meta name=\"author\" content=\"Orator\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Orator\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/merkel-macht-den-hitler\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/merkel-macht-den-hitler\\\/\"},\"author\":{\"name\":\"Orator\",\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/#\\\/schema\\\/person\\\/5b30b80e385478896a1de221e1994d86\"},\"headline\":\"Merkel macht den Hitler\",\"datePublished\":\"2016-02-17T18:43:30+00:00\",\"dateModified\":\"2016-02-17T18:45:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/merkel-macht-den-hitler\\\/\"},\"wordCount\":299,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/#\\\/schema\\\/person\\\/5b30b80e385478896a1de221e1994d86\"},\"keywords\":[\"Endsieg\",\"Gr\u00f6FaZ\",\"Gr\u00f6KaZ\",\"Hitler\",\"Merkel\",\"Volksverrat\"],\"articleSection\":[\"Denunzianten und Volksverr\u00e4ter\",\"Die d\u00fcmmsten Spr\u00fcche der Woche\",\"Gedanken zum Tag\",\"Systemfehler\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/merkel-macht-den-hitler\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/merkel-macht-den-hitler\\\/\",\"url\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/merkel-macht-den-hitler\\\/\",\"name\":\"Merkel macht den Hitler - Zeitgeist? Frei!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/#website\"},\"datePublished\":\"2016-02-17T18:43:30+00:00\",\"dateModified\":\"2016-02-17T18:45:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/merkel-macht-den-hitler\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/merkel-macht-den-hitler\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/merkel-macht-den-hitler\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Merkel macht den Hitler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/#website\",\"url\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/\",\"name\":\"Zeitgeist? Frei!\",\"description\":\"Was Ihr den Geist der Zeiten hei\u00dft...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/#\\\/schema\\\/person\\\/5b30b80e385478896a1de221e1994d86\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/#\\\/schema\\\/person\\\/5b30b80e385478896a1de221e1994d86\",\"name\":\"Orator\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g\",\"caption\":\"Orator\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g\"},\"url\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/author\\\/1korrektor21-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Merkel macht den Hitler - Zeitgeist? Frei!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/merkel-macht-den-hitler\/","og_locale":"de_DE","og_type":"article","og_title":"Merkel macht den Hitler - Zeitgeist? Frei!","og_description":"Wie die Geschichte sich doch immer wiederholt. Propagierte der Gr\u00f6FaZ angesichts der sich abzeichnenden Niederlage immer vehementer den \u201eEndsieg\u201c, der, so sein Reichsminister f\u00fcr Volksaufkl\u00e4rung und Propaganda, Joseph Goebbels, nur mittels \u201etotalem Krieg\u201c zu erreichen sei, schwadroniert die Gr\u00f6KaZ kognitiv &hellip; Weiterlesen &rarr;","og_url":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/merkel-macht-den-hitler\/","og_site_name":"Zeitgeist? Frei!","article_published_time":"2016-02-17T18:43:30+00:00","article_modified_time":"2016-02-17T18:45:18+00:00","author":"Orator","twitter_misc":{"Verfasst von":"Orator","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/merkel-macht-den-hitler\/#article","isPartOf":{"@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/merkel-macht-den-hitler\/"},"author":{"name":"Orator","@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/#\/schema\/person\/5b30b80e385478896a1de221e1994d86"},"headline":"Merkel macht den Hitler","datePublished":"2016-02-17T18:43:30+00:00","dateModified":"2016-02-17T18:45:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/merkel-macht-den-hitler\/"},"wordCount":299,"commentCount":0,"publisher":{"@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/#\/schema\/person\/5b30b80e385478896a1de221e1994d86"},"keywords":["Endsieg","Gr\u00f6FaZ","Gr\u00f6KaZ","Hitler","Merkel","Volksverrat"],"articleSection":["Denunzianten und Volksverr\u00e4ter","Die d\u00fcmmsten Spr\u00fcche der Woche","Gedanken zum Tag","Systemfehler"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/merkel-macht-den-hitler\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/merkel-macht-den-hitler\/","url":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/merkel-macht-den-hitler\/","name":"Merkel macht den Hitler - Zeitgeist? Frei!","isPartOf":{"@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/#website"},"datePublished":"2016-02-17T18:43:30+00:00","dateModified":"2016-02-17T18:45:18+00:00","breadcrumb":{"@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/merkel-macht-den-hitler\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/merkel-macht-den-hitler\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/merkel-macht-den-hitler\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/"},{"@type":"ListItem","position":2,"name":"Merkel macht den Hitler"}]},{"@type":"WebSite","@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/#website","url":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/","name":"Zeitgeist? Frei!","description":"Was Ihr den Geist der Zeiten hei\u00dft...","publisher":{"@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/#\/schema\/person\/5b30b80e385478896a1de221e1994d86"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/#\/schema\/person\/5b30b80e385478896a1de221e1994d86","name":"Orator","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g","caption":"Orator"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g"},"url":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/author\/1korrektor21-2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/posts\/1006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/comments?post=1006"}],"version-history":[{"count":3,"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/posts\/1006\/revisions"}],"predecessor-version":[{"id":1009,"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/posts\/1006\/revisions\/1009"}],"wp:attachment":[{"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/media?parent=1006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/categories?post=1006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/tags?post=1006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}