{"id":2311,"date":"2020-11-19T15:29:43","date_gmt":"2020-11-19T13:29:43","guid":{"rendered":"http:\/\/www.inkultura-online.de\/politisch_unkorrekt\/?p=2311"},"modified":"2020-11-19T15:32:26","modified_gmt":"2020-11-19T13:32:26","slug":"die-wahren-feinde-der-demokratie","status":"publish","type":"post","link":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/die-wahren-feinde-der-demokratie\/","title":{"rendered":"Die wahren Feinde der Demokratie"},"content":{"rendered":"<p>Alle (namentlich <a href=\"https:\/\/www.bundestag.de\/resource\/blob\/807344\/cc9a7b0cd38b5370ec8703f74b2b9326\/20201118_3-data.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">die<\/a> hier), denen schon immer die vom erlaubten Mainstream abweichende politische Meinung des B\u00fcrgers ein Dorn im Auge war, k\u00f6nnen jetzt frohlocken. Das in Rekordzeit durch die Instanzen gepeitschte <a href=\"https:\/\/dip21.bundestag.de\/dip21\/btd\/19\/239\/1923944.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Erm\u00e4chtigungsgesetz<\/a>, Verzeihung, das \u201eGesetz zum Schutz der Bev\u00f6lkerung bei einer epidemischen Lage von nationaler Tragweite\u201c, das nichtsdestotrotz gut zwei Dutzend Mal von \u201eerm\u00e4chtigen\u201c spricht, ist dazu da, die widerspenstigen B\u00fcrger, die, die sich partout nicht damit abfinden wollen, wie die Regierungsclique mit tatkr\u00e4ftiger Hilfe des inzwischen vom Staat alimentierten polit-medialen Kartell sukzessive die Freiheit des Einzelnen beschneidet, zu disziplinieren.<!--more--><\/p>\n<p>Bei jeder Ausrufung welch auch immer einer Pandemie \u2013 auch die j\u00e4hrlich auftretende Grippe d\u00fcrfte bald unter diese Rubrik fallen \u2013 erh\u00e4lt ein zuk\u00fcnftiger Bundesgesundheitsminister, der dann vielleicht \u00fcber die Qualifikation eines abgebrochenen was auch immer Studiums verf\u00fcgt, das Recht und die M\u00f6glichkeit, wie es im Artikel 7 des Erm\u00e4chtigungsgesetzes zu lesen ist, die <b>Einschr\u00e4nkung von Grundrechten<\/b> anordnen zu k\u00f6nnen.<\/p>\n<p>W\u00f6rtlich hei\u00dft es:<\/p>\n<p>Durch Artikel 1 Nummer 16 und 1 werden die Grundrechte der Freiheit der Person (Artikel 2 Absatz 2 Satz 2 des Grundgesetzes), der Versammlungsfreiheit (Artikel 8 des Grundgesetzes), der Freiz\u00fcgigkeit (Artikel 11 Absatz 1 des Grundgesetzes) und der Unverletzlichkeit der Wohnung (Artikel 13 Absatz 1 des Grundgesetzes) eingeschr\u00e4nkt.<\/p>\n<p>Wer immer noch der irrigen Meinung ist, die Regierung h\u00e4tte in den vergangenen Monaten und w\u00fcrde in der Zukunft vern\u00fcnftiges und zielf\u00fchrendes Handeln an den Tag gelegt, um die Ausbreitung der sog. Corona-Epidemie zu verhindern, der d\u00fcrfte angesichts der bisher angewandten und zuk\u00fcnftig durch das Erm\u00e4chtigungsgesetz drohenden Ma\u00dfnahmen eines Besseren belehrt worden sein.<\/p>\n<p>So fanden und finden im gro\u00dfen Stil die Beerdigungen von Personen krimineller Gro\u00dffamilien zwar ohne Abstandsregeln, daf\u00fcr jedoch unter Polizeischutz statt. Die B\u00fcrger sollen \u201esoziale Kontakte\u201c vermeiden, doch im Berufsverkehr Arsch an Arsch mit den \u00f6ffentlichen Verkehrsmitteln fahren, die, im Gegensatz zu den L\u00e4ndern Asiens, die die sog. Epidemie l\u00e4ngst \u00fcberwunden haben, nicht mehrmals t\u00e4glich desinfiziert werden.<\/p>\n<p>Die Alten und Kranken sterben einsam in den unter staatlicher Beteiligung privatisierten Pflegeh\u00f6llen, w\u00e4hrend \u2013 welche Klientel feiert da wohl \u2013 \u201eFamilienfeiern\u201c, so der Sprachgebrauch der \u00d6ffentlich-Rechtlichen-Verdummung munter vonstattengehen.<\/p>\n<p>Da werden friedliche Demonstranten, unter denen sich sowohl Familien mit Kindern als auch um ihre Existenz k\u00e4mpfende Menschen befinden, die allesamt ihr Recht zur Meinungs\u00e4u\u00dferung wahrnehmen, von den Staatsmedien kriminalisiert und \u2013 in Berlin \u2013 von Wasserwerfern der Polizei maltr\u00e4tiert oder \u2013 in Leipzig \u2013 vom kriminellem Arm der Merkel-Junta, von den sog. Autonomen mit Gewalt an ihrem Recht zu demonstrieren gehindert.<\/p>\n<p>Covid-19 ist zweifelsohne f\u00fcr manche Menschen ein t\u00f6dlicher Virus, f\u00fcr die \u00fcberwiegende Mehrheit, so ernst zu nehmende Wissenschaftler wie <a href=\"https:\/\/www.inkultura-online.de\/fehlalarm.html\" target=\"_blank\" rel=\"noopener noreferrer\">Karina Reiss und Sucharit Bhakdi<\/a>, jedoch bestenfalls der Ausl\u00f6ser unbestimmter Unannehmlichkeiten, der nur allzu gerne von den Politikern dazu benutzt wird, die Welt, wie wir sie kennen, durch diktatorische Ma\u00dfnahmen zu ver\u00e4ndern.<\/p>\n<p>W\u00e4re die sog. Corona-Epidemie nicht ausgebrochen, interessierte Kreise, genauer gesagt, gelangweilte Milliard\u00e4re mit politischem Sendungsbed\u00fcrfnis und sog. Nichtregierungsorganisationen, also allesamt demokratisch nicht legitimierte Interessengruppen, h\u00e4tten sie erfinden m\u00fcssen, um ihre Pl\u00e4ne f\u00fcr den \u201eGreat Reset\u201c, den gro\u00dfen Neustart f\u00fcr eine Welt nach ihren perversen Vorstellungen, durchsetzen zu k\u00f6nnen.<\/p>\n<p>Der UN-Migrationspakt und sein kleiner europ\u00e4ischer Bruder, der EU-Migrationspakt und die daraus folgenden Umsiedlungen schwarz- und nordafrikanischer Menschen nach Europa, d\u00fcrfte von den hier lebenden Autochthonen nicht ohne Widerstand akzeptiert werden. Ebenso d\u00fcrfte die unter staatlicher Aufsicht und politischer F\u00f6rderung stattfindende Islamisierung des europ\u00e4ischen Kontinents durch sog. \u201eFl\u00fcchtlinge\u201c aus muslimisch gepr\u00e4gten L\u00e4ndern, die offen und unverhohlen unsere Gesellschaftsordnung ablehnen, f\u00fcr weitere Konflikte mit den hier \u201ebereits l\u00e4nger lebenden Menschen\u201c (Die Diktion der Gr\u00f6KaZ) sorgen.<\/p>\n<p>Dazu kommt der von den etablierten Parteien, vom Kartell der B\u00fcrgerfeinde, forciert betriebene Wahnsinn eines angeblich anthropogenen Klimawandels, der nur abgewendet werden kann, wenn die industrialisierte Welt auf alles verzichtet, was die CO2-Bilanz erh\u00f6ht.<\/p>\n<p>Da passt es doch ganz ausgezeichnet, dass ausgerechnet jetzt eine Pandemie aufgetreten ist, die es erforderlich macht, mit diktatorischen Ma\u00dfnahmen die Rechte der B\u00fcrger auf vielf\u00e4ltige Weise einzuschr\u00e4nken. Ein Schelm, wer B\u00f6ses dabei denkt.<\/p>\n<p><b>Noch einmal zum Mitdenken:<\/b><\/p>\n<p>Artikel 7 des Erm\u00e4chtigungsgesetzes, Verzeihung, des \u201eGesetzes zum Schutz der Bev\u00f6lkerung bei einer epidemischen Lage von nationaler Tragweite\u201c<\/p>\n<p>Durch Artikel 1 Nummer 16 und 1 werden die Grundrecht der Freiheit der Person (Artikel 2 Absatz 2 Satz 2 des Grundgesetzes), der Versammlungsfreiheit (Artikel 8 des Grundgesetzes), der Freiz\u00fcgigkeit (Artikel 11 Absatz 1 des Grundgesetzes) und der Unverletzlichkeit der Wohnung (Artikel 13 Absatz 1 des Grundgesetzes) eingeschr\u00e4nkt.<\/p>\n<p>Vielleicht ist es h\u00f6chste Zeit \u2013 oder die letzte M\u00f6glichkeit \u2013 zum \u2026 oder zur \u2026 zu greifen?!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alle (namentlich die hier), denen schon immer die vom erlaubten Mainstream abweichende politische Meinung des B\u00fcrgers ein Dorn im Auge war, k\u00f6nnen jetzt frohlocken. Das in Rekordzeit durch die Instanzen gepeitschte Erm\u00e4chtigungsgesetz, Verzeihung, das \u201eGesetz zum Schutz der Bev\u00f6lkerung bei &hellip; <a href=\"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/die-wahren-feinde-der-demokratie\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,378,7,30,10,11],"tags":[1445,1447,1444,1446,336],"class_list":["post-2311","post","type-post","status-publish","format-standard","hentry","category-antipathie","category-denunzianten","category-moderne-zeiten","category-so-siehts-aus","category-systemfehler","category-was-die-qualitaetspresse-gern-verschweigt","tag-corona-pandemie","tag-die-wahren-feinde-der-demokratie","tag-ermaechtigungsgesetz","tag-great-reset","tag-neue-weltordnung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die wahren Feinde der Demokratie - Zeitgeist? Frei!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/die-wahren-feinde-der-demokratie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die wahren Feinde der Demokratie - Zeitgeist? Frei!\" \/>\n<meta property=\"og:description\" content=\"Alle (namentlich die hier), denen schon immer die vom erlaubten Mainstream abweichende politische Meinung des B\u00fcrgers ein Dorn im Auge war, k\u00f6nnen jetzt frohlocken. Das in Rekordzeit durch die Instanzen gepeitschte Erm\u00e4chtigungsgesetz, Verzeihung, das \u201eGesetz zum Schutz der Bev\u00f6lkerung bei &hellip; Weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/die-wahren-feinde-der-demokratie\/\" \/>\n<meta property=\"og:site_name\" content=\"Zeitgeist? Frei!\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-19T13:29:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-19T13:32:26+00:00\" \/>\n<meta name=\"author\" content=\"Orator\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Orator\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/die-wahren-feinde-der-demokratie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/die-wahren-feinde-der-demokratie\\\/\"},\"author\":{\"name\":\"Orator\",\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/#\\\/schema\\\/person\\\/5b30b80e385478896a1de221e1994d86\"},\"headline\":\"Die wahren Feinde der Demokratie\",\"datePublished\":\"2020-11-19T13:29:43+00:00\",\"dateModified\":\"2020-11-19T13:32:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/die-wahren-feinde-der-demokratie\\\/\"},\"wordCount\":782,\"publisher\":{\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/#\\\/schema\\\/person\\\/5b30b80e385478896a1de221e1994d86\"},\"keywords\":[\"Corona-Pandemie\",\"Die wahren Feinde der Demokratie\",\"Erm\u00e4chtigungsgesetz\",\"Great Reset\",\"Neue Weltordnung\"],\"articleSection\":[\"Antipathie\",\"Denunzianten und Volksverr\u00e4ter\",\"Moderne Zeiten\",\"So sieht\u00b4s aus\",\"Systemfehler\",\"Was die \\\"Qualit\u00e4tspresse\\\" gern verschweigt\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/die-wahren-feinde-der-demokratie\\\/\",\"url\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/die-wahren-feinde-der-demokratie\\\/\",\"name\":\"Die wahren Feinde der Demokratie - Zeitgeist? Frei!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/#website\"},\"datePublished\":\"2020-11-19T13:29:43+00:00\",\"dateModified\":\"2020-11-19T13:32:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/die-wahren-feinde-der-demokratie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/die-wahren-feinde-der-demokratie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/die-wahren-feinde-der-demokratie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die wahren Feinde der Demokratie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/#website\",\"url\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/\",\"name\":\"Zeitgeist? Frei!\",\"description\":\"Was Ihr den Geist der Zeiten hei\u00dft...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/#\\\/schema\\\/person\\\/5b30b80e385478896a1de221e1994d86\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/#\\\/schema\\\/person\\\/5b30b80e385478896a1de221e1994d86\",\"name\":\"Orator\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g\",\"caption\":\"Orator\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g\"},\"url\":\"https:\\\/\\\/www.inkultura-online.de\\\/politisch_unkorrekt\\\/author\\\/1korrektor21-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die wahren Feinde der Demokratie - Zeitgeist? Frei!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/die-wahren-feinde-der-demokratie\/","og_locale":"de_DE","og_type":"article","og_title":"Die wahren Feinde der Demokratie - Zeitgeist? Frei!","og_description":"Alle (namentlich die hier), denen schon immer die vom erlaubten Mainstream abweichende politische Meinung des B\u00fcrgers ein Dorn im Auge war, k\u00f6nnen jetzt frohlocken. Das in Rekordzeit durch die Instanzen gepeitschte Erm\u00e4chtigungsgesetz, Verzeihung, das \u201eGesetz zum Schutz der Bev\u00f6lkerung bei &hellip; Weiterlesen &rarr;","og_url":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/die-wahren-feinde-der-demokratie\/","og_site_name":"Zeitgeist? Frei!","article_published_time":"2020-11-19T13:29:43+00:00","article_modified_time":"2020-11-19T13:32:26+00:00","author":"Orator","twitter_misc":{"Verfasst von":"Orator","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/die-wahren-feinde-der-demokratie\/#article","isPartOf":{"@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/die-wahren-feinde-der-demokratie\/"},"author":{"name":"Orator","@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/#\/schema\/person\/5b30b80e385478896a1de221e1994d86"},"headline":"Die wahren Feinde der Demokratie","datePublished":"2020-11-19T13:29:43+00:00","dateModified":"2020-11-19T13:32:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/die-wahren-feinde-der-demokratie\/"},"wordCount":782,"publisher":{"@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/#\/schema\/person\/5b30b80e385478896a1de221e1994d86"},"keywords":["Corona-Pandemie","Die wahren Feinde der Demokratie","Erm\u00e4chtigungsgesetz","Great Reset","Neue Weltordnung"],"articleSection":["Antipathie","Denunzianten und Volksverr\u00e4ter","Moderne Zeiten","So sieht\u00b4s aus","Systemfehler","Was die \"Qualit\u00e4tspresse\" gern verschweigt"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/die-wahren-feinde-der-demokratie\/","url":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/die-wahren-feinde-der-demokratie\/","name":"Die wahren Feinde der Demokratie - Zeitgeist? Frei!","isPartOf":{"@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/#website"},"datePublished":"2020-11-19T13:29:43+00:00","dateModified":"2020-11-19T13:32:26+00:00","breadcrumb":{"@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/die-wahren-feinde-der-demokratie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/die-wahren-feinde-der-demokratie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/die-wahren-feinde-der-demokratie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/"},{"@type":"ListItem","position":2,"name":"Die wahren Feinde der Demokratie"}]},{"@type":"WebSite","@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/#website","url":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/","name":"Zeitgeist? Frei!","description":"Was Ihr den Geist der Zeiten hei\u00dft...","publisher":{"@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/#\/schema\/person\/5b30b80e385478896a1de221e1994d86"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/#\/schema\/person\/5b30b80e385478896a1de221e1994d86","name":"Orator","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g","caption":"Orator"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/96e03166d31716e9c437060430eb7605c45a8ce6fb6dab483637ca6915dd0844?s=96&d=mm&r=g"},"url":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/author\/1korrektor21-2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/posts\/2311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/comments?post=2311"}],"version-history":[{"count":3,"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/posts\/2311\/revisions"}],"predecessor-version":[{"id":2314,"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/posts\/2311\/revisions\/2314"}],"wp:attachment":[{"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/media?parent=2311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/categories?post=2311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inkultura-online.de\/politisch_unkorrekt\/wp-json\/wp\/v2\/tags?post=2311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}